{"id":14788,"date":"2025-05-26T08:21:18","date_gmt":"2025-05-26T08:21:18","guid":{"rendered":"https:\/\/staging-hz.snk-dev.de\/?post_type=insight&#038;p=14788"},"modified":"2025-10-29T09:03:59","modified_gmt":"2025-10-29T09:03:59","slug":"vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl","status":"publish","type":"insight","link":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/","title":{"rendered":"TPI Podcast #14"},"content":{"rendered":"","protected":false},"featured_media":5415,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"topic":[],"industry":[],"insight-type":[140],"other_tag":[155],"solution":[113],"class_list":["post-14788","insight","type-insight","status-publish","has-post-thumbnail","hentry","insight-type-podcast","other_tag-tpi","solution-einkauf-und-kostenmanagement"],"acf":{"short_text":"Alexander Pilsl von TeamViewer zeigt, wie orchestrierte Beschaffung Engp\u00e4sse l\u00f6st und Gesch\u00e4ftswert steigert.","related_insights":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl<\/title>\n<meta name=\"description\" content=\"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/\" \/>\n<meta property=\"og:site_name\" content=\"H&amp;Z\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T09:03:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hz.group\/wp-content\/uploads\/2025\/08\/Episode_14_SAWOO_image_6f812192d7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/\",\"url\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/\",\"name\":\"Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hz.group\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Episode_14_SAWOO_image_6f812192d7.jpg\",\"datePublished\":\"2025-05-26T08:21:18+00:00\",\"dateModified\":\"2025-10-29T09:03:59+00:00\",\"description\":\"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hz.group\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Episode_14_SAWOO_image_6f812192d7.jpg\",\"contentUrl\":\"https:\\\/\\\/hz.group\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Episode_14_SAWOO_image_6f812192d7.jpg\",\"width\":800,\"height\":800,\"caption\":\"Procurement Initiative Leaders podcast cover Orchestrate or Stagnate with TeamViewer Director Alexander Pilsl | H&Z\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/insight\\\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hz.group\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TPI Podcast #14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hz.group\\\/de\\\/\",\"name\":\"H&Z Unternehmensberatung\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hz.group\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#organization\",\"name\":\"H&Z Group\",\"url\":\"https:\\\/\\\/hz.group\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hz.group\\\/wp-content\\\/uploads\\\/static\\\/hz_logo-3.svg\",\"contentUrl\":\"https:\\\/\\\/hz.group\\\/wp-content\\\/uploads\\\/static\\\/hz_logo-3.svg\",\"caption\":\"H&Z Group\"},\"image\":{\"@id\":\"https:\\\/\\\/hz.group\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl","description":"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/","og_locale":"de_DE","og_type":"article","og_title":"Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl","og_description":"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.","og_url":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/","og_site_name":"H&amp;Z","article_modified_time":"2025-10-29T09:03:59+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/hz.group\/wp-content\/uploads\/2025\/08\/Episode_14_SAWOO_image_6f812192d7.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/","url":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/","name":"Beschaffungsstrategie optimieren \u2013 Podcast mit Alexander Pilsl","isPartOf":{"@id":"https:\/\/hz.group\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/#primaryimage"},"image":{"@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/#primaryimage"},"thumbnailUrl":"https:\/\/hz.group\/wp-content\/uploads\/2025\/08\/Episode_14_SAWOO_image_6f812192d7.jpg","datePublished":"2025-05-26T08:21:18+00:00","dateModified":"2025-10-29T09:03:59+00:00","description":"Erfahren Sie im Podcast, wie moderne Beschaffungsstrategie, Digitalisierung Einkauf und Lieferkettenmanagement bei TeamViewer den Gesch\u00e4ftserfolg steigern.","breadcrumb":{"@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/#primaryimage","url":"https:\/\/hz.group\/wp-content\/uploads\/2025\/08\/Episode_14_SAWOO_image_6f812192d7.jpg","contentUrl":"https:\/\/hz.group\/wp-content\/uploads\/2025\/08\/Episode_14_SAWOO_image_6f812192d7.jpg","width":800,"height":800,"caption":"Procurement Initiative Leaders podcast cover Orchestrate or Stagnate with TeamViewer Director Alexander Pilsl | H&Z"},{"@type":"BreadcrumbList","@id":"https:\/\/hz.group\/de\/insight\/vierzehnte-folge-des-procurement-initiative-leaders-podcast-mit-alexander-pilsl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hz.group\/de\/"},{"@type":"ListItem","position":2,"name":"TPI Podcast #14"}]},{"@type":"WebSite","@id":"https:\/\/hz.group\/de\/#website","url":"https:\/\/hz.group\/de\/","name":"H&Z Unternehmensberatung","description":"","publisher":{"@id":"https:\/\/hz.group\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hz.group\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hz.group\/de\/#organization","name":"H&Z Group","url":"https:\/\/hz.group\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hz.group\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hz.group\/wp-content\/uploads\/static\/hz_logo-3.svg","contentUrl":"https:\/\/hz.group\/wp-content\/uploads\/static\/hz_logo-3.svg","caption":"H&Z Group"},"image":{"@id":"https:\/\/hz.group\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/insight\/14788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/insight"}],"about":[{"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/types\/insight"}],"version-history":[{"count":28,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/insight\/14788\/revisions"}],"predecessor-version":[{"id":23885,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/insight\/14788\/revisions\/23885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/media\/5415"}],"wp:attachment":[{"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/media?parent=14788"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/topic?post=14788"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/industry?post=14788"},{"taxonomy":"insight-type","embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/insight-type?post=14788"},{"taxonomy":"other_tag","embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/other_tag?post=14788"},{"taxonomy":"solution","embeddable":true,"href":"https:\/\/hz.group\/de\/wp-json\/wp\/v2\/solution?post=14788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}